{"id":20577,"date":"2022-12-22T13:07:26","date_gmt":"2022-12-22T12:07:26","guid":{"rendered":"https:\/\/www.dottorgiorgini.it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/"},"modified":"2025-12-18T13:31:47","modified_gmt":"2025-12-18T12:31:47","slug":"meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini","status":"publish","type":"product","link":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/","title":{"rendered":"Meteovis 500ml analcolico per l&#8217;eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini"},"content":{"rendered":"<p><strong>Meteovis 500 ml liquido analcoolico &#8211; dr. Giorgini<\/strong><\/p>\n<p>Integratore appositamente studiato per favorire l&#8217;eliminazione dei gas intestinali e contrastare la flatulenza post-prandiale<\/p>\n<p>Disponibile anche nel formato da 200ml<\/p>\n<p><strong>Funzionalit\u00e0 degli ingredienti<\/strong><\/p>\n<p>Finocchio, anice verde, anice stellato, cardamomo, coriandolo, menta, angelica di Boemia e melissa aiutano la funzione digestiva e favoriscono la regolare motilit\u00e0 gastrointestinale e l\u2019eliminazione dei gas.<\/p>\n<p><strong>Consigli d&#8217;uso<\/strong><\/p>\n<p>Si consiglia l\u2019assunzione di 10 ml diluiti in un bicchiere d&#8217;acqua, una o due volte al giorno in qualunque momento (da 10 a 20 ml al giorno); suggerito durante i pasti.<\/p>\n<p>Se desiderato, la dose giornaliera pu\u00f2 essere diluita in una bottiglia d\u2019acqua da consumare nell\u2019arco della giornata.<\/p>\n<p>Agitare prima dell\u2019uso.<\/p>\n<p>Misurino graduato incluso nella confezione.<\/p>\n<p>Conservare il prodotto fuori dal frigorifero anche dopo l\u2019apertura.<br \/>\nNaturali caratteristiche distintive:\u00a0Sapore gradevole<\/p>\n<p><strong>Ingredienti<\/strong><\/p>\n<p>Glicerina vegetale bidistillata, acqua pura, finocchio (Foeniculum vulgare) frutti E.I.L., anice verde (Pimpinella anisum) frutti E.I.L., anice stellato (Illicium verum) frutti E.I.L., liquirizia (Glycyrrhiza glabra) radici E.S. (titolato al 18-22% in acido glicirrizico o glicirrizina), balsamite odorosa (Chrysanthemum balsamita) erba E.I.L., cardamomo (Elettaria cardamomum) semi E.I.L., condurango (Marsdenia condurango) cortecce dell\u2019albero E.I.L., coriandolo (Coriandrum sativum) frutti E.I.L., cannella (Cinnamomum zeylanicum) cortecce E.I.L., menta piperita (Mentha piperita) foglie E.I.L., angelica di Boemia (Angelica archangelica) radici E.I.L., melissa (Melissa officinalis) foglie E.I.L.; edulcoranti di origine naturale: glicosidi steviolici e taumatina.<br \/>\nCon edulcoranti di origine naturale.<br \/>\nE.S.= Estratto secco. E.I.L.= Estratto integrale liquido.<\/p>\n<p><strong>Tabella nutrizionale presente nelle immagini del prodotto<\/strong>.<\/p>\n<p><strong>Adatto ai vegani.<br \/>\n<\/strong><\/p>\n<p><strong>Senza ingredienti derivati da animali.<br \/>\n<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Meteovis 500 ml liquido analcoolico &#8211; dr. Giorgini Integratore appositamente studiato per favorire l&#8217;eliminazione dei gas intestinali e contrastare la flatulenza post-prandiale Disponibile anche nel formato da 200ml Funzionalit\u00e0 degli ingredienti Finocchio, anice verde, anice stellato, cardamomo, coriandolo, menta, angelica di Boemia e melissa aiutano&#8230;<\/p>\n","protected":false},"featured_media":1000000117857,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[2934],"product_tag":[],"giftcard-category":[],"class_list":{"0":"post-20577","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-dr-apparato-digerente","7":"pa_formato-500-ml","8":"pa_linea-linea-oro","9":"pa_marca-dr-giorgini","10":"pa_tipologia-liquido-analcolico","12":"first","13":"instock","14":"sale","15":"taxable","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.9 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Meteovis 500ml analcolico per l&#039;eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini - dottorgiorgini.it<\/title>\n<meta name=\"description\" content=\"Integratore appositamente studiato per favorire l&#039;eliminazione dei gas intestinali e contrastare la flatulenza post-prandiale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Meteovis 500ml analcolico per l&#039;eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini - dottorgiorgini.it\" \/>\n<meta property=\"og:description\" content=\"Integratore appositamente studiato per favorire l&#039;eliminazione dei gas intestinali e contrastare la flatulenza post-prandiale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/\" \/>\n<meta property=\"og:site_name\" content=\"dottorgiorgini.it\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T12:31:47+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/\",\"url\":\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/\",\"name\":\"Meteovis 500ml analcolico per l'eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini - dottorgiorgini.it\",\"isPartOf\":{\"@id\":\"https:\/\/www.dottorgiorgini.it\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dottorgiorgini.it\/wp-content\/uploads\/2022\/12\/00009796.jpeg\",\"datePublished\":\"2022-12-22T12:07:26+00:00\",\"dateModified\":\"2025-12-18T12:31:47+00:00\",\"description\":\"Integratore appositamente studiato per favorire l'eliminazione dei gas intestinali e contrastare la flatulenza post-prandiale\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#primaryimage\",\"url\":\"https:\/\/www.dottorgiorgini.it\/wp-content\/uploads\/2022\/12\/00009796.jpeg\",\"contentUrl\":\"https:\/\/www.dottorgiorgini.it\/wp-content\/uploads\/2022\/12\/00009796.jpeg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dottorgiorgini.it\/it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\/\/www.dottorgiorgini.it\/it\/negozio\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Meteovis 500ml analcolico per l&#8217;eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dottorgiorgini.it\/en\/#website\",\"url\":\"https:\/\/www.dottorgiorgini.it\/en\/\",\"name\":\"dottorgiorgini.it\",\"description\":\"Erbe e Integratori Naturali\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dottorgiorgini.it\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Meteovis 500ml analcolico per l'eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini - dottorgiorgini.it","description":"Integratore appositamente studiato per favorire l'eliminazione dei gas intestinali e contrastare la flatulenza post-prandiale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/","og_locale":"it_IT","og_type":"article","og_title":"Meteovis 500ml analcolico per l'eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini - dottorgiorgini.it","og_description":"Integratore appositamente studiato per favorire l'eliminazione dei gas intestinali e contrastare la flatulenza post-prandiale","og_url":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/","og_site_name":"dottorgiorgini.it","article_modified_time":"2025-12-18T12:31:47+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/","url":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/","name":"Meteovis 500ml analcolico per l'eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini - dottorgiorgini.it","isPartOf":{"@id":"https:\/\/www.dottorgiorgini.it\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#primaryimage"},"image":{"@id":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dottorgiorgini.it\/wp-content\/uploads\/2022\/12\/00009796.jpeg","datePublished":"2022-12-22T12:07:26+00:00","dateModified":"2025-12-18T12:31:47+00:00","description":"Integratore appositamente studiato per favorire l'eliminazione dei gas intestinali e contrastare la flatulenza post-prandiale","breadcrumb":{"@id":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#primaryimage","url":"https:\/\/www.dottorgiorgini.it\/wp-content\/uploads\/2022\/12\/00009796.jpeg","contentUrl":"https:\/\/www.dottorgiorgini.it\/wp-content\/uploads\/2022\/12\/00009796.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.dottorgiorgini.it\/it\/prodotto\/meteovis-500ml-analcolico-per-leliminazione-dei-gas-intestinali-e-il-contrasto-flatulenza-post-prandiale-dr-giorgini\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dottorgiorgini.it\/it\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/www.dottorgiorgini.it\/it\/negozio\/"},{"@type":"ListItem","position":3,"name":"Meteovis 500ml analcolico per l&#8217;eliminazione dei gas intestinali e il contrasto flatulenza post-prandiale dr. Giorgini"}]},{"@type":"WebSite","@id":"https:\/\/www.dottorgiorgini.it\/en\/#website","url":"https:\/\/www.dottorgiorgini.it\/en\/","name":"dottorgiorgini.it","description":"Erbe e Integratori Naturali","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dottorgiorgini.it\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/wp\/v2\/product\/20577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/wp\/v2\/media?parent=20577"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/wp\/v2\/product_brand?post=20577"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/wp\/v2\/product_cat?post=20577"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/wp\/v2\/product_tag?post=20577"},{"taxonomy":"giftcard-category","embeddable":true,"href":"https:\/\/www.dottorgiorgini.it\/it\/wp-json\/wp\/v2\/giftcard-category?post=20577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}